{"id":31172,"date":"2026-07-05T23:16:00","date_gmt":"2026-07-05T22:16:00","guid":{"rendered":"https:\/\/pickleballfans.eu\/nl\/toernooi-v2\/european-padel-pickleball-open-barcelona-2026\/"},"modified":"2026-07-05T23:16:00","modified_gmt":"2026-07-05T22:16:00","slug":"european-padel-pickleball-open-barcelona-2026","status":"publish","type":"pbf_toernooi","link":"https:\/\/pickleballfans.eu\/en\/toernooi-v2\/european-padel-pickleball-open-barcelona-2026\/","title":{"rendered":"European Padel &amp; Pickleball Open Barcelona 2026"},"content":{"rendered":"<p>Meer info + inschrijving op de organisator-site.<\/p>","protected":false},"excerpt":{"rendered":"<p>Groot Europees toernooi, alleen extern inschrijven.<\/p>","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-31172","pbf_toernooi","type-pbf_toernooi","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/pickleballfans.eu\/en\/wp-json\/wp\/v2\/pbf_toernooi\/31172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pickleballfans.eu\/en\/wp-json\/wp\/v2\/pbf_toernooi"}],"about":[{"href":"https:\/\/pickleballfans.eu\/en\/wp-json\/wp\/v2\/types\/pbf_toernooi"}],"author":[{"embeddable":true,"href":"https:\/\/pickleballfans.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/pickleballfans.eu\/en\/wp-json\/wp\/v2\/pbf_toernooi\/31172\/revisions"}],"wp:attachment":[{"href":"https:\/\/pickleballfans.eu\/en\/wp-json\/wp\/v2\/media?parent=31172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}